{"id":1640,"date":"2015-07-15T16:05:54","date_gmt":"2015-07-15T14:05:54","guid":{"rendered":"https:\/\/mktfactory.com\/blog\/?p=1640"},"modified":"2015-07-15T16:33:50","modified_gmt":"2015-07-15T14:33:50","slug":"perche-avere-un-blog","status":"publish","type":"post","link":"https:\/\/mktfactory.com\/blog\/perche-avere-un-blog\/","title":{"rendered":"Perch\u00e9 dovresti avere un blog"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1643\" src=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2015\/07\/vantaggi-nellavere-un-blog.jpg\" alt=\"vantaggi nell'avere un blog\" width=\"750\" height=\"400\" \/><br \/>\nPer ogni ricerca che effettui su Google noterai sempre una cosa. Tra i 10 risultati che escono c&#8217;\u00e8 quasi sempre un blog di mezzo o \u00e8 un&#8217;azienda che possiede un blog.<\/p>\n<p>Il termine \u00e8 stato usato per la prima volta nel 1997 come &#8220;weblog&#8221; per poi successivamente dividersi in &#8220;we blog&#8221; ed infine semplicemente in &#8220;blog&#8221;.<\/p>\n<p>Quindi perch\u00e9 dovresti avere un blog?<\/p>\n<h2>PIACE AI MOTORI DI RICERCA<\/h2>\n<p>I blogs piacciono particolarmente ai motori di ricerca per la loro facile indicizzazione e per la loro utilit\u00e0 all&#8217;utente finale.<\/p>\n<p>Infatti ci\u00f2 che ogni motore di ricerca vuole ottenere \u00e8 la soddisfazione dei propri utilizzatori.<\/p>\n<p>I blogs danno risposte alle domande e creano un legame tra lo scrittore e il lettore.<\/p>\n<h2>TRAFFICO <\/h2>\n<p>Il traffico \u00e8 la risorsa numero 1 per vincere online. Senza traffico non c&#8217;\u00e8 azienda, di nessun tipo.<\/p>\n<p>Perci\u00f2 dobbiamo sempre trovare nuove maniere per ottenere questo traffico e riuscire a sopravvivere in un mondo cos\u00ec competitivo come quello odierno fatto di nuove tecnologie e di internet.<\/p>\n<p>Il blog \u00e8 la maniera migliore per <a href=\"https:\/\/mktfactory.com\/blog\/super-tecniche-per-portare-traffico-al-tuo-sito-web\/\">portare traffico al tuo sito<\/a> o al tuo prodotto o servizio.<\/p>\n<p>Per avere traffico attraverso il blog devi avere una costanza nel creare contenuti.<\/p>\n<p>Cerca di crearli sufficientemente lunghi o unici visto che l&#8217;abbondanza di valore \u00e8 ci\u00f2 che decreta la sua visibilit\u00e0 sui motori di ricerca e genera condivisioni social.<\/p>\n<p>Ovviamente non dimenticare di installare i classici pulsanti di condivisione.<\/p>\n<h2>BRANDING <\/h2>\n<p>Per essere conosciuta la tua azienda deve essere esposta a molte persone. Se hai solo un sito di statiche che aspetta di essere visitato allora non stai facendo niente per incrementare il brand.<\/p>\n<p>Scrivendo per il blog hai la possibilit\u00e0 di estendere la tua <a href=\"https:\/\/mktfactory.com\/blog\/come-fare-networking\/\">cerchia di conoscenze<\/a> ben oltre le tue aspettative. Cos\u00ec il tuo brand avr\u00e0 un esposizione maggiore.<\/p>\n<p>Solitamente, il tuo brand deve essere visto almeno 7 volte prima che un potenziale cliente compri da te.<\/p>\n<p>Perci\u00f2 non devi attendere passivamente. Potrebbero passare anni prima che vedano sette volte il tuo brand.<\/p>\n<p>Scrivi regolarmente per il blog e avrai tutto nel pi\u00f9 breve tempo possibile.<\/p>\n<p>Per\u00f2, il blog da&#8217; valore al brand solamente se il blog stesso \u00e8 di valore, altrimenti comunica la scarsa competenza e mancanza di professionalit\u00e0.<\/p>\n<p>Due cose che nessun brand vorrebbe avere come etichette.<\/p>\n<h2>VENDITE<\/h2>\n<p><a href=\"https:\/\/mktfactory.com\/blog\/perche-le-aziende-non-crescono\/\">Nessuna azienda sopravvive senza vendere<\/a>, almeno che non scrocca da investitori o creditori. Ma nessuno \u00e8 cos\u00ec generoso da tenere in piedi un&#8217;azienda che non vende per un lungo periodo.<\/p>\n<p>Secondo diverse ricerche le aziende che hanno un blog aumentano le vendite anche pi\u00f9 del 50% rispetto a quelle che non lo hanno.<\/p>\n<p>Non scordare mai che devi prima guadagnarti la fiducia dei tuoi potenziali clienti. Ed \u00e8 per questo che scrivi per il blog.<\/p>\n<p>Il blog ha gi\u00e0 fatto l&#8217;80% della vendita perch\u00e9 avere la fiducia \u00e8 in assoluto la cosa pi\u00f9 difficile da ottenere nel business.<\/p>\n<p>Con tutta questa concorrenza, con le scarse risorse, con l&#8217;abbondanza di offerta.<\/p>\n<h2>COMMUNITY<\/h2>\n<p>Dietro ogni azienda di successo si nasconde una community di ferro, fatta di persone appassionate del brand in questione.<\/p>\n<p>Le community formate da fans sono tra le risorse pi\u00f9 preziose che un&#8217;azienda pu\u00f2 avere perch\u00e9 diventano egli stessi dei promotori dei prodotti e servizi.<\/p>\n<p>Basta che pensi ai fans della Apple o della Harley Davidson che si tatuano il brand addosso.<\/p>\n<p>Con il blog puoi piano piano col tempo costruire una community di persone che hai aiutato e che vogliono condividere con te le loro storie o raccontare le difficolt\u00e0 che stanno affrontando.<\/p>\n<p>Dandoti cos\u00ec le idee per creare nuovi prodotti e risolvere i loro problemi.<\/p>\n<p>E&#8217; un dare\/avere che pu\u00f2 andare avanti all&#8217;infinito.<\/p>\n<p>La community la puoi iniziare a creare permettendo a chi lo vuole di commentare i tuoi articoli.<\/p>\n<p>In secondo luogo generare una newsletter che utilizzerai successivamente per organizzare degli eventi oppure per creare dei membership sites.<\/p>\n<p>Cosi da creare una community interna e protetta dalle influenze esterne. Un po&#8217; come Facebook.<\/p>\n<p>Rispondi il pi\u00f9 possibile ai commenti e se hai tempo vai anche su altri blogs a commentare. Cosi altri bloggers e la loro audience se sono curiosi e vogliono ricambiare verranno a commentare da te.<\/p>\n<p>Alla fine di ogni articolo prova a fare una domanda per stimolare l&#8217;aggiunta dei commenti.<\/p>\n<p>Sicuramente il tuo blog \u00e8 pieno di distrazione e troppe call to action che l&#8217;utente, anche volendo commentare viene portato via da qualche distrazione.<\/p>\n<h2>CONOSCENZA<\/h2>\n<p>Diciamo la verit\u00e0. Non puoi essere un buon scrittore senza prima essere un buon lettore.<br \/>\nLe informazioni le devi assorbire da qualche parte.<\/p>\n<p>E&#8217; proprio questa continua ricerca di informazione da masticare che ti creano un bagaglio di conoscenze non indifferenti.<\/p>\n<p>Pi\u00f9 intendi scrivere, pi\u00f9 devi conoscere.<\/p>\n<p>Imparare l&#8217;arte della lettura\/scrittura ti pu\u00f2 essere utile in mille altri lavori. Inoltre il tuo cervello viene esteso a considerare sempre cose nuove da pi\u00f9 punti di vista.<\/p>\n<p>E&#8217; come il cuoco che ogni settimana devo fare un piatto che non ha mai fatto prima.<\/p>\n<p>Gli ingredienti nella natura sono sempre gli stessi ma il processo di creazione \u00e8 diverso ogni volta.<\/p>\n<h2>DISCIPLINA<\/h2>\n<p>Se vuoi avere un blog non puoi non essere disciplinato. E&#8217; un lavoro metodico e ripetitivo.<\/p>\n<p>Se pensi di non essere disciplinato allora dovresti proprio fare blogging ed imparare questa nuova skill che pu\u00f2 essere decisamente utile per tutte le restanti cose della tua vita.<\/p>\n<p>La disciplina inoltre ti mette la pace dei sensi perch\u00e9, con essa dalla tua parte sei cosciente di poter fare tutto ci\u00f2 che vuoi.<\/p>\n<p>Non andrai mai pi\u00f9 in crisi e non sarai mai pi\u00f9 in difficolt\u00e0 economiche se la disciplina \u00e8 dalla tua parte.<\/p>\n<p>Devi semplicemente continuare nel tuo processo giorno dopo giorno.<\/p>\n<h2>AMICIZIE<\/h2>\n<p>Sebbene il processo di creazione \u00e8 quasi sempre un atto solitario. Quello di promozione \u00e8 tutt&#8217;altro.<\/p>\n<p>Infatti nella seconda fase si tratta di vera e propria consegna del messaggio.<\/p>\n<p>Devi consegnare la tua arte nelle mani di persone che conosci e di persone che non conosci.<\/p>\n<p>Questo atto ti dar\u00e0 la possibilit\u00e0 di incontrare persone nuove e di restare in contatto con quelle vecchie.<\/p>\n<p>Sono delle relazioni professionali che arricchiscono la tua vita.<\/p>\n<p>Tra l&#8217;altro nessun blogger ce l&#8217;ha fatto senza le amicizie di percorso. Senza quelle persone che l&#8217;hanno sostenuto un articolo dopo un altro.<\/p>\n<p>Chi \u00e8 che non vorrebbe avere nella propria vita coloro che lo sostengono?<\/p>\n<p>Non solo forse le persone migliori da avere vicino a te? Coloro che ti spingono a dare il massimo e si congratulano con te ogni volta che vinci.<\/p>\n<p>E&#8217; decisamente una vita in crescita.<\/p>\n<h2>MAILING LIST<\/h2>\n<p>Il blog \u00e8 senza alcun dubbio il canale principale per <a href=\"http:\/\/mktfactory.com\/podcast\/come-aumentare-gli-iscritti-alla-newsletter\/\">incrementare gli iscritti alla tua mailing list<\/a>.<\/p>\n<p>Infatti un articolo del blog \u00e8 di per s\u00e9 una dimostrazione di valore che tu offri al lettore gratuitamente.<\/p>\n<p>Nella maggior parte dei casi il lettore vorr\u00e0 di pi\u00f9 e per avere questo &#8220;pi\u00f9&#8221; da te \u00e8 disposto a darti la sua email.<\/p>\n<p>Ci deve essere sempre uno scambio equo.<\/p>\n<p>Maggior \u00e8 il valore del tuo articolo maggiore sar\u00e0 l&#8217;offerta dall&#8217;altra parte.<\/p>\n<p>Tutto il tuo business dovrebbe girare intorno alla mailing list.<\/p>\n<p>Perch\u00e9 \u00e8 proprio questa risorsa che ti sar\u00e0 affianco per molto tempo. E quando vedrai svanire un social network dopo un altro e con essi tutti followers raccolti negli anni di duro lavoro.<\/p>\n<p>Avere la mailing list sar\u00e0 per te un vero sollievo. Nonch\u00e9 un vantaggio competitivo contro coloro che non si sono attrezzati per tempo.<\/p>\n<h2>LEADERSHIP<\/h2>\n<p>Scrivere articoli per il blog \u00e8 una delle maniere pi\u00f9 rapidi per diventare esperti di settore e assumere una posizione di autorevolezza.<\/p>\n<p>Infatti non a caso i bloggers sono invitati ovunque a parlare delle loro conoscenze. In televisione, alla radio, alle conferenze, ai <a href=\"http:\/\/mktfactory.com\/podcast\">podcasts<\/a> e via dicendo.<\/p>\n<p>Logicamente serve del tempo prima di prendere una certa mano nello scrivere. Per sbloccare la proprio creativit\u00e0, per trovare la propria regolarit\u00e0 e motivazione.<\/p>\n<p>Per\u00f2 se c&#8217;\u00e8 la determinazione dovresti diventare un leader nel campo in pochi anni con i tuoi articoli.<\/p>\n<p>La vera leadership \u00e8 nella dimostrazione.<\/p>\n<p>Non puoi chiedere ai tuoi clienti di fare un investimento grande nei tuoi prodotti se tu non hai dimostrato di sacrificarti per il loro bene.<\/p>\n<p>Non c&#8217;\u00e8 peggior leader di colui che predica bene e razzola male. Predica duro lavoro ma lui predilige l&#8217;ozio. Predica passione ma lui \u00e8 indifferente.<\/p>\n<p>Fare blogging \u00e8 un sacrificio per il bene del tuo cliente. E&#8217; in questo sacrificio si vedr\u00e0 la tua leadership senza che tu dica una parola in tuo favore.<\/p>\n<h2>E&#8217; FACILE<\/h2>\n<p>Creare un blog oggigiorno \u00e8 abbastanza facile. Hai solo bisogno di acquistare un buon <a href=\"http:\/\/www.siteground.com\/index.htm?afcode=92cb301406020500858dde9804011b88&#038;campaign=Blog_Header\" target=\"_blank\">hosting<\/a> ed installare WordPress tramite la loro piattaforma.<\/p>\n<h2>CONCLUSIONE<\/h2>\n<p>Poche cose sono cos\u00ec efficaci sul web come il blog. Non a caso ce ne sono pi\u00f9 di 500 milioni al mondo e continuano ad aumentare.<\/p>\n<p>Per vedere i suoi benefici devi solo iniziare. Con un po&#8217; di determinazione e persistenza il tuo business vedr\u00e0 un enorme salita che ti sorprender\u00e0.<\/p>\n<p>Ma non prenderla alla leggera. Non \u00e8 una cosa per i pigri.<\/p>\n<p>Puoi ascoltare questa intervista podcast su <a href=\"http:\/\/mktfactory.com\/podcast\/come-fare-blogging\/\">come fare blogging<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per ogni ricerca che effettui su Google noterai sempre una cosa. Tra i 10 risultati che escono c&#8217;\u00e8 quasi sempre un blog di mezzo o \u00e8 un&#8217;azienda che possiede un blog. Il termine \u00e8 stato usato per la prima volta nel 1997 come &#8220;weblog&#8221; per poi successivamente dividersi in &#8220;we blog&#8221; ed infine semplicemente in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1643,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[31,17,7],"tags":[],"class_list":{"0":"post-1640","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-content-marketing","8":"category-marketing","9":"category-seo","10":"entry"},"featured_image_src":"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2015\/07\/vantaggi-nellavere-un-blog.jpg","featured_image_src_square":"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2015\/07\/vantaggi-nellavere-un-blog.jpg","author_info":{"display_name":"Dino Gojanovic","author_link":"https:\/\/mktfactory.com\/blog\/author\/mkt\/"},"_links":{"self":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts\/1640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/comments?post=1640"}],"version-history":[{"count":14,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts\/1640\/revisions"}],"predecessor-version":[{"id":1655,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts\/1640\/revisions\/1655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/media\/1643"}],"wp:attachment":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/media?parent=1640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/categories?post=1640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/tags?post=1640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}