{"id":213,"date":"2012-11-13T00:38:24","date_gmt":"2012-11-12T22:38:24","guid":{"rendered":"http:\/\/mktfactory.com\/blog\/?p=213"},"modified":"2019-11-26T21:12:59","modified_gmt":"2019-11-26T19:12:59","slug":"come-posizionare-il-brand","status":"publish","type":"post","link":"https:\/\/mktfactory.com\/blog\/come-posizionare-il-brand\/","title":{"rendered":"Come posizionare il Brand?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3102\" src=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2012\/11\/Come-posizionare-il-brand.jpg\" alt=\"come posizionare il brand\" width=\"800\" height=\"500\" srcset=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2012\/11\/Come-posizionare-il-brand.jpg 800w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2012\/11\/Come-posizionare-il-brand-300x188.jpg 300w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2012\/11\/Come-posizionare-il-brand-768x480.jpg 768w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2012\/11\/Come-posizionare-il-brand-600x375.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Il posizionamento consiste nel definire l&#8217;offerta e l&#8217;immagine della nostra impresa in modo tale da consentirle di occupare una posizione distinta e apprezzata nella mente del mercato obiettivo.<\/p>\n<p>Il posizionamento non \u00e8 l&#8217;intervento su un prodotto. Il posizionamento \u00e8 l&#8217;intervento sulla mente del potenziale destinatario della comunicazione.<\/p>\n<p>Ecco 5 fattori su cui puntare per ottenere un buon posizionamento del brand:<\/p>\n<p><strong>1. Quali sono gli attributi del brand<\/strong><\/p>\n<p>Cosa riesce a trasmettere il nostro brand attraverso le caratteristiche e vantaggi al consumatore.<\/p>\n<p>E&#8217; unico e distintivo? E&#8217; memorabile?<\/p>\n<p><strong>2. Quali sono le aspettative dei consumatori<\/strong><\/p>\n<p>Che cosa i consumatori si aspettano di ricevere dal brand?<\/p>\n<p>Si aspettano la qualit\u00e0 oppure la quantit\u00e0?<\/p>\n<p>Si aspettano consegna veloce oppure lenta?<\/p>\n<p>Si aspettano un servizio clienti efficiente o mediocre?<\/p>\n<p><strong>3. Quale \u00e8 il potenziale dei concorrenti<\/strong><\/p>\n<p>Che cosa offrono i concorrenti nel nostro mercato e quali sono le loro caratteristiche e vantaggi per il consumatore.<\/p>\n<p><strong>4. Come \u00e8 il prezzo<\/strong><\/p>\n<p>Semplicemente, il nostro prezzo contro il prezzo della concorrenza.<\/p>\n<p>Cosa dice il <a href=\"https:\/\/mktfactory.com\/podcast\/058-come-aumentare-i-prezzi\/\">prezzo del tuo brand<\/a>?<\/p>\n<p><strong>5. La percezione del consumatore<\/strong><\/p>\n<p>Come il consumatore percepisce nella sua mente la qualit\u00e0 e il <a href=\"https:\/\/mktfactory.com\/blog\/strategia-acquisizione-clienti-non-funziona\/\">valore del nostro brand.<\/a><\/p>\n\n\n<h4 class=\"wp-block-heading\">Conclusione<\/h4>\n\n\n\n<p>Posizionare il proprio brand in un mondo sempre pi\u00f9 globalizzato richiede impegno e metodo.<\/p>\n\n\n\n<p>Un ottimo punto di partenza \u00e8 leggere il famoso libro <a href=\"https:\/\/amzn.to\/33pZ9xg\" target=\"_blank\" rel=\"noreferrer noopener nofollow\" aria-label=\"Il Posizionamento (apre in una nuova scheda)\">Il Posizionamento<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il posizionamento consiste nel definire l&#8217;offerta e l&#8217;immagine della nostra impresa in modo tale da consentirle di occupare una posizione distinta e apprezzata nella mente del mercato obiettivo. Il posizionamento non \u00e8 l&#8217;intervento su un prodotto. Il posizionamento \u00e8 l&#8217;intervento sulla mente del potenziale destinatario della comunicazione. Ecco 5 fattori su cui puntare per ottenere [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[17],"tags":[42,41],"class_list":{"0":"post-213","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-marketing","7":"tag-brand-positioning","8":"tag-branding","9":"entry","10":"has-post-thumbnail"},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Dino Gojanovic","author_link":"https:\/\/mktfactory.com\/blog\/author\/mkt\/"},"_links":{"self":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts\/213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/comments?post=213"}],"version-history":[{"count":10,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts\/213\/revisions"}],"predecessor-version":[{"id":3148,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts\/213\/revisions\/3148"}],"wp:attachment":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/media?parent=213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/categories?post=213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/tags?post=213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}