{"id":2463,"date":"2017-11-09T16:38:50","date_gmt":"2017-11-09T14:38:50","guid":{"rendered":"https:\/\/mktfactory.com\/blog\/?p=2463"},"modified":"2020-09-24T19:17:38","modified_gmt":"2020-09-24T17:17:38","slug":"come-diventare-esperti-di-settore","status":"publish","type":"post","link":"https:\/\/mktfactory.com\/blog\/come-diventare-esperti-di-settore\/","title":{"rendered":"Come diventare esperti di settore"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2476\" src=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2017\/11\/Come-diventare-un-esperto-nel-proprio-settore.png\" alt=\"Esperti nel proprio settore\" width=\"800\" height=\"1100\" srcset=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2017\/11\/Come-diventare-un-esperto-nel-proprio-settore.png 800w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2017\/11\/Come-diventare-un-esperto-nel-proprio-settore-218x300.png 218w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2017\/11\/Come-diventare-un-esperto-nel-proprio-settore-768x1056.png 768w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2017\/11\/Come-diventare-un-esperto-nel-proprio-settore-745x1024.png 745w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2017\/11\/Come-diventare-un-esperto-nel-proprio-settore-600x825.png 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>In ogni settore c&#8217;\u00e8 una piccola fetta di fenomeni che prende tutti i guadagni, lasciando agli altri solo briciole.<\/p>\n<p>Chi sono questi fenomeni?<\/p>\n<p>Questi Guuuurrruuuu.<\/p>\n<p>Sono i cosiddetti leader di mercato.<\/p>\n<p>Solitamente una manciata di essi controlla l&#8217;80% del mercato.<\/p>\n<p>E&#8217; gente ultra specializzata.<\/p>\n<p>Super competitiva.<\/p>\n<p>Nella maggior parte dei casi hanno dedicato la loro vita alla carriera e sacrificato tutto il resto.<\/p>\n<p>Perci\u00f2 se punti a fargli concorrenza \u00e8 meglio se ti prepari a dovere.<\/p>\n<h2>Trova un settore che ti appassiona<\/h2>\n<p>Avere qualcosa che ti attira inconsciamente \u00e8 un vantaggio. Puoi iniziare con questi punti.<\/p>\n<p><b>Fai una lista<\/b><\/p>\n<p>Ecco un consiglio di Warren Buffet:<\/p>\n<ol>\n<li>Scrivi una lista di 25 cose che vorresti fare nella vita.<\/li>\n<li>Evidenziane 5 che pi\u00f9 ti convincono.<\/li>\n<li>Queste saranno quelle che farai da qui in poi.<\/li>\n<li>Le restanti 20 sono da evitare a tutti i costi. Sarebbero solo una distrazione in pi\u00f9.<\/li>\n<\/ol>\n<p>Questo \u00e8 un metodo estremo per la focalizzazione e la prioritizzazione.<\/p>\n<p>Insomma, fai poco e non pensare ad altro.<\/p>\n<p><b>Chi sono i tuoi miti?<\/b><\/p>\n<p>Sicuramente hai una lista di persone che stimi. Imprenditori, attori, <a href=\"https:\/\/mktfactory.com\/blog\/abitudini-grandi-artisti-miliardari-e-geni\/\">artisti<\/a>, scrittori etc.<\/p>\n<p>E\u2019 venuto il momento di metterli su carta perch\u00e9 ci dovremo ragionare sopra.<\/p>\n<p>Stila gi\u00f9 un bel elenco di almeno 25 persone da tenere d&#8217;occhio.<\/p>\n<p>Compra dei libri sulle loro biografie e vedi se possono corrispondere ad un tuo immaginario.<\/p>\n<p><b>Sperimenta cose<\/b><\/p>\n<p>Come fai a sapere se \u00e8 meglio fare il pilota di auto o moto se non hai mai provato nessuna delle due opzioni?<\/p>\n<p>Come fai a sapere se \u00e8 meglio suonare la chitarra o il basso se non hai mai provato nessuna delle due?<\/p>\n<p>Insomma, hai afferrato il concetto.<\/p>\n<p>Bisogna sperimentare le cose della vita per essere vivi.<\/p>\n<p>Per saper scegliere bisogna sapere cosa c\u2019\u00e8 dentro il frigo.<\/p>\n<p>Ovviamente c\u2019\u00e8 il rischio di sbagliare. Si pu\u00f2 essere criticati.<\/p>\n<p>Per questo si tende a non assapporare troppe cose nuove. A non uscire troppo dal guscio.<\/p>\n<p>Ma senza aver esercitato il palato si pu\u00f2 solo aspirare ad una carriera mediocre.<\/p>\n<p><b>Chiedi ad amici o parenti<\/b><\/p>\n<p>Chiedere agli amici o parenti un consiglio sulla tua persona pu\u00f2 essere un buon esperimento.<\/p>\n<p>Loro sicuramente conoscono i tuoi punti di forza e debolezza.<\/p>\n<p>Dopotutto ti hanno osservato per anni nelle tue azioni quotidiane e possono darti un suggerimento su quello che potresti fare con maestria.<\/p>\n<p>Cosa \u00e8 secondo loro un compito che fai bene e senza sforzi?<\/p>\n<p>Prova e vedrai.<\/p>\n<p>Alcuni sanno subito cosa gli appassiona mentre altri sono pieni di dubbi.<\/p>\n<p>Questo dipende molto da come hai vissuto e dagli stimoli e insegnamenti che hai ricevuto.<\/p>\n<h2>Focalizzati su una cosa sola<\/h2>\n<p>Un buon libro sull&#8217;argomento \u00e8 <a href=\"http:\/\/amzn.to\/2AtmmS4\" target=\"_blank\" rel=\"noopener noreferrer\">Una cosa sola<\/a> di Gary Keller.<\/p>\n<p>Lui suggerisce di eliminare praticamente quasi tutto.<\/p>\n<p>Ed \u00e8 un po&#8217; simile ai consigli di Warren Buffet.<\/p>\n<p>Questo concetto fa anche parte della saggezza popolare ma spesso si dimentica.<\/p>\n<p>In questo mondo pieno di caos dove tutto sembra una novit\u00e0 che schiaccia le cose vecchie, bisogna sempre rispolverare quelle cose che funzionano.<\/p>\n<p>Non tutto ci\u00f2 che \u00e8 nuovo \u00e8 da prendere e non tutto ci\u00f2 che \u00e8 vecchio \u00e8 da buttare.<\/p>\n<p><b>Metti i paletti alle opportunit\u00e0<\/b><\/p>\n<p>Le opportunit\u00e0 sono pericolose.<\/p>\n<p>Ti distraggono dal tuo compito principale.<\/p>\n<p>Perci\u00f2 valuta con attenzione.<\/p>\n<p><b>Ignora i trend<\/b><br \/>\nIl 90% delle mode del momento svaniranno con la fine del mese.<\/p>\n<p>Perci\u00f2 non ti devi far risucchiare dalla scintillante novit\u00e0 senza un&#8217;attenta analisi.<\/p>\n<p>Ricordati che ci\u00f2 che hai sottomano ha bisogno di tempo.<br \/>\nSei sicuro che quel poco di tempo che hai lo vuoi dedicare a tutti i trend che passano?<\/p>\n<p>Ignora la maggior parte di essi. I restanti che hanno del valore tienili d\u2019occhio.<\/p>\n<p><b>Attento ai social media<\/b><\/p>\n<p>Un&#8217;altro bel libro \u00e8 <a href=\"http:\/\/amzn.to\/2iFC04P\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Deep Work<\/a>.<\/p>\n<p>L&#8217;autore spiega che con l&#8217;arrivo dell&#8217;intelligenza artificiale solo i lavori che richiedono profondi ragionamenti, elevata creativit\u00e0 o empatia saranno disponibili.<\/p>\n<p>I lavori ripetitivi o quelli che richiedono poco intelletto verranno completamente rimpiazzati.<\/p>\n<p>Ordunque, la tua concentrazione profonda ti pu\u00f2 salvare.<\/p>\n<p>Non la sprecare con la <a href=\"https:\/\/mktfactory.com\/blog\/regole-sopravvivere-social-networks\/\">dipendenza da social<\/a>.<\/p>\n<p>Devi usare i social ma non devi essere dipendente dai social.<\/p>\n<p>Segui la regola dello spacciatore che non deve consumare la propria merce.<\/p>\n<p><a href=\"https:\/\/www.mktfactory.com\/newsletter\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2703\" src=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2017\/06\/1.png\" alt=\"Diventa un insider, iscriviti alla newsletter\" width=\"567\" height=\"842\" srcset=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2017\/06\/1.png 567w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2017\/06\/1-202x300.png 202w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/a><\/p>\n<h2>Rendi la pratica perfetta<\/h2>\n<p>Sappiamo tutti che la perfezione non esiste e non bisogna tormentarsi con essa.<\/p>\n<p>Ma devi comunque puntare in alto.<\/p>\n<p>Perch\u00e9?<\/p>\n<p>Perch\u00e9 \u00e8 difficile. Ecco il perch\u00e9.<\/p>\n<p>Se fosse facile non miglioreresti. Si migliora solo con le <a href=\"https:\/\/mktfactory.com\/blog\/come-trasformare-difficolta-opportunita\/\">difficolt\u00e0<\/a>.<\/p>\n<p>Quindi, inseguire un&#8217;ideale difficile ti rende una persona migliore e pi\u00f9 capace.<\/p>\n<p><b>Organizza la giornata<\/b><br \/>\nSai come \u00e8 il detto. Se non \u00e8 sul calendario allora non \u00e8 importante.<\/p>\n<p>Devi organizzare le tue giornate. Non puoi pensare di competere con la concorrenza vivendo come un collegiale.<\/p>\n<p>Organizza la giornata nel miglior modo possibile.<\/p>\n<p>Evita le liste to-do ma punta invece sul modello calendario.<\/p>\n<p>Cio\u00e8, metti le cose da fare nel calendario, con l\u2019ora in cui intendi fare il compito.<\/p>\n<p>La migliore maniera di organizzarsi il lavoro \u00e8 sempre quello del buon vecchio calendario.<\/p>\n<p>Le to-do list a mio avviso creano pi\u00f9 confusione che altro.<\/p>\n<p>Se hai delle facende da fare mettile sul calendario direttamente.<\/p>\n<p>E poi metti degli avvisi che ti ricordano di fare certe cose.<\/p>\n<p>Google Calendar \u00e8 sempre il migliore per questo.<\/p>\n<p><b>Rispetta le scadenze<\/b><br \/>\nNessuno vuole fare affari con qualcuno che non rispetta le scadenze.<\/p>\n<p>E se una volta non c\u2019era molta concorrenza oggi ce ne fin troppa.<\/p>\n<p>Questo significa che il tuo cliente ti scaricher\u00e0 senza pensarci due volte se gli manchi di precisione.<\/p>\n<p>Rispetta le scadenze. Pianifica in anticipo ed esegui senza esitazione.<\/p>\n<p><b>Evita le urgenze altrui<\/b><br \/>\nC\u2019\u00e8 gente che semplicemente non ha disciplina e finisce perennemente nei casini.<\/p>\n<p>Che poi vorr\u00e0 scaricarti addosso.<\/p>\n<p>Non far diventare le urgenze altrui tue.<\/p>\n<p>Certo, ci sono cose importanti e urgenti delle quali non puoi non occuparti.<\/p>\n<p>Ma la maggior parte delle cose urgenti non sono importanti e non sono nemmeno tue.<\/p>\n<p>Allontanati da queste situazioni.<\/p>\n<p>Moltissime persone in gamba si sono viste far una vita mediocre perch\u00e9 avevano intorno a s\u00e9 persone di questo tipo.<\/p>\n<p>Rischi di vivere una vita di riparazione dei casini altrui. Per giunta gratis.<\/p>\n<p><b>Attento alla noia<\/b><br \/>\nQuando il compito diventa noioso si tende ad abbandonarlo.<\/p>\n<p>Abbandonarlo per\u00f2 non \u00e8 una buona idea.<\/p>\n<p>La cosa migliore da fare \u00e8 di usare un trucco.<\/p>\n<p>Divertirsi.<\/p>\n<p>In sostanza introduci del gioco dentro al compito noioso.<\/p>\n<p>Oggi lo chiamano Gamification. Ed \u00e8 decisamente efficiente.<\/p>\n<h2>Impossessati del territorio di lavoro<\/h2>\n<p>Devi controllare il territorio per delle ragioni che conosci benissimo.<\/p>\n<p>Chi controlla riesce a prevedere. Chi viene controllato invece vive in un perenne stato di ansia perch\u00e9 non riesce a prevedere niente.<\/p>\n<p><b>Impara il Local SEO<\/b><\/p>\n<p>Il Local Seo \u00e8 quella pratica di ottimizzazione per i motori di ricerca al livello locale.<\/p>\n<p>Cio\u00e8, nel tuo circondario geografico.<\/p>\n<p>Questa \u00e8 una delle maniere migliori per impossessarti del territorio.<\/p>\n<p>Lo sai anche tu che tutti cercano su Google.<\/p>\n<p>Solitamente cercano per comprare.<\/p>\n<p>E quando cercano per comprare e tu sei davanti ai loro occhi, allora hai buone probabilit\u00e0 di acquisire un nuovo cliente.<\/p>\n<p>Sono in pochi quelli che cercano un idraulico sulle vecchie pagine gialle oggigiorno.<\/p>\n<p>Forse qualche pensionato affezzionato ai vecchi tempi. Ma anche loro oggi con gli smartphone iniziano a darsi da fare.<\/p>\n<p>Tra qualche anno con gli assistenti virtuali sempre pi\u00f9 intelligenti tipo Google Assistant, Siri il vecchietto non avr\u00e0 di che preoccuparsi.<\/p>\n<p><b>Iscriviti o crea i Meetup<\/b><\/p>\n<p>Meetup \u00e8 un sito web che ti aiuta a trovare dei gruppi con la tua stessa passione o necessit\u00e0.<\/p>\n<p>Potrai conoscere tantissime persone nuove.<\/p>\n<p><b>Iscriviti alle associazioni di categoria<\/b><br \/>\nCi sono tantissime organizzazione che hanno scopi di lobbying.<\/p>\n<p>In sostanza proteggono i loro interessi. Ma anche i tuoi se entri a far parte della loro organizzazione.<\/p>\n<p>Se non ti sei accorto, la societ\u00e0 civile \u00e8 piena di gruppi che mirano alla sopravvivenza dei suoi membri.<\/p>\n<p>Frequenta i posti giusti e tutto ti sar\u00e0 pi\u00f9 facile.<\/p>\n<h2>Delega cose di poco valore<\/h2>\n<p>Scopri cosa vale e cosa non vale.<\/p>\n<p>Dovresti sapere con precisione la differenza.<\/p>\n<p>Sembra un&#8217;affermazione scontata e semplice ma in realt\u00e0 \u00e8 tra le cose pi\u00f9 difficili che esistono.<\/p>\n<p>Sapere cosa vale \u00e8 dannatamente difficile.<\/p>\n<p>Ad esempio 1 bitcoin vale qualcosa?<\/p>\n<p>Quanto vale?<\/p>\n<p>Se no, perch\u00e9 non vale?<\/p>\n<p>Vale perch\u00e9 gli altri dicono che vale?<\/p>\n<p>Non vale perch\u00e9 \u00e8 solo un pezzettino di codice e niente altro?<\/p>\n<p>Possiamo farci le domande all&#8217;infinito e non trovare la verit\u00e0.<\/p>\n<p>Per\u00f2 sapere cosa vale e cosa non vale \u00e8 fondamentale per il successo a lungo termine di ogni cosa.<\/p>\n<p>E sebbene non avrai la verit\u00e0 definitiva anche una parziale ti potrebbe salvare.<\/p>\n<p><b>Scopri dove trovare manodopera<\/b><br \/>\nGuarda sempre quali sono i posti che frequentano le persone straordinarie nel tuo settore.<\/p>\n<p>In quali community stanno?<\/p>\n<p>Una volta scoperta la location cerca di frequentarla.<\/p>\n<p>Sar\u00e0 un\u2019ottima fonte dalla quale attingere nei momenti del bisogno.<\/p>\n<p>Insomma, cerca di non fare tutto all\u2019ultimo minuto.<\/p>\n<p><b>Commissiona i lavori<\/b><\/p>\n<p>Inizia a far pratica da subito. Commissiona anche i piccolissimi lavori che potresti fare da solo.<\/p>\n<p>Lo devi fare perch\u00e9 delegare \u00e8 una pratica che si impara col tempo.<\/p>\n<p>Ed \u00e8 meglio iniziare da subito ad esercitarla prima che arrivino i grossi lavori e con essi grosso stress.<\/p>\n<p>Non vai a cantare in uno stadio pieno di persone se prima non hai cantato nei piccoli pub.<\/p>\n<p>E\u2019 un suicidio.<\/p>\n<h2>Crea valore continuamente<\/h2>\n<p><b>Guarda cosa fa la concorrenza e fai di meglio<\/b><br \/>\nUna delle ottime maniere e abbastanza veloci per trovare idee di valore \u00e8 di guardare la concorrenza.<\/p>\n<p>Per copiare?<\/p>\n<p>No, per fare meglio ci\u00f2 che fanno.<\/p>\n<p>Si prende ispirazione. Tutto qui.<\/p>\n<p>Non tutto ci\u00f2 che fanno viene effettivamente apprezzato dai loro clienti.<\/p>\n<p>Perci\u00f2 avrai bisogno di un occhio attento per scovare quali sono le vere gemme e poi farle meglio.<\/p>\n<p><b>Chiedi ai clienti quali problemi hanno e risolvili<\/b><\/p>\n<p>Una maniera rapida per avere del cash \u00e8 di chiedere ai clienti quali sono i loro maggior problemi.<\/p>\n<p>Una volta scoperti si pu\u00f2 tracciare una linea, ragionarci sopra e cercare di vedere una strada per poterli risolvere.<\/p>\n<p>Se ci riesci hai risolto anche i tuoi problemi oltre ai loro.<\/p>\n<h2>Evita i vampiri del tempo<\/h2>\n<p><b>Rendi difficile il contatto diretto con te<\/b><\/p>\n<p>Ci sono persone che si annoiano sempre. Questo lo sai.<\/p>\n<p>E queste persone cercano sempre qualcuno che li intrattenga.<\/p>\n<p>Hanno bisogno di passare del tempo e non sapendo come fare, decidono di contattare te.<\/p>\n<p>Se la prima volta \u00e8 stata un successo, riproveranno anche in futuro.<\/p>\n<p>Pi\u00f9 tu gli dai divertimento pi\u00f9 ritorneranno da te nei periodi di noia.<\/p>\n<p>E&#8217; una cosa positiva se anche tu ti annoi. Hai trovato qualcuno come te.<\/p>\n<p>E&#8217; una cosa negativa se tu hai un business da mandare in avanti e fai fatica a trovare il tempo anche per la famiglia.<\/p>\n<p>Questi vampiri del tempo si annidano sopratutto sui social.<\/p>\n<p>Attendono che tu metta la testa fuori un secondo e ti catturano subito con i loro messaggi.<\/p>\n<p>E a fine serata ti domanderai come mai non hai combinato niente per tutta la giornata.<\/p>\n<p>La disciplina del lavoro \u00e8 facile da spezzare ma difficile da riavere.<\/p>\n<p>Non perderla.<\/p>\n<p><b>Seleziona le persone<\/b><\/p>\n<p>Le persone non sono tutte uguali. Anche se nell&#8217;immaginario collettivo c\u2019\u00e8 il senso dell\u2019uguaglianza ma in realt\u00e0 la natura non \u00e8 egalitaria.<\/p>\n<p>Alla natura non importa se tu sia buono e gentile. Se stai sotto ad un vulcano in eruzione verrai spazzato via.<\/p>\n<p>Cos\u00ec \u00e8 il tuo rapporto con le persone.<\/p>\n<p>Se frequenti persone narcisiste quelle ti distruggeranno. Non importa quanto tu sia una brava persona.<\/p>\n<p>La loro natura \u00e8 semplicemente distruttiva per quelli che li circondano.<\/p>\n<p>Perci\u00f2, abbi sempre un&#8217;apertura per le nuove conoscenze ma non esitare a cambiare strada se ci\u00f2 che vedi non \u00e8 di tuo gradimento.<\/p>\n<h2>Automatizza tutto<\/h2>\n<p>Oggi ci sono software per automatizzare quasi tutto e tu devi fare in modo di utilizzarli.<\/p>\n<p>Perch\u00e9?<\/p>\n<p>Perch\u00e9 la tua concorrenza lo fa. Ed ha un vantaggio competitivo su di te.<\/p>\n<p>Se sei bravo con la automazione puoi fare il lavoro di un&#8217;intera agenzia da solo. Ma logicamente, serve maestria e quella non \u00e8 semplice da avere.<\/p>\n<p><b>Usa IFTTT<\/b><br \/>\nUn bellissimo servizio per l&#8217;automazione \u00e8 <a href=\"https:\/\/ifttt.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">IFTTT<\/a> oppure Zapier.<\/p>\n<p>Puoi automatizzare le cose ripetitive che fai solitamente.<\/p>\n<p>Ad esempio inviare sui social un articolo appena pubblicato con WordPress.<\/p>\n<p>Oppure mettere nel calendario un evento prestabilito.<\/p>\n<p>Insomma, sui loro siti hanno molte idee che ti possono essere utili. Dai un&#8217;occhiata.<\/p>\n<p><b>Usa il cloud<\/b><br \/>\nOrmai l\u2019avrai capito. I lavori del futuro li puoi svolgere stando ovunque.<\/p>\n<p>I documenti saranno tutti on the cloud. Probabilmente utilizzando la tecnologia Blockchain di cui sicuramente hai sentito parlare.<\/p>\n<p>Per intenderci \u00e8 la tecnologia sulla quale gira Bitcoin.<\/p>\n<p>Ed \u00e8 molto promettente.<\/p>\n<p><b>Usa l\u2019intelligenza artificiale<\/b><\/p>\n<p>Da quando ho scritto l\u2019articolo sull&#8217;<a href=\"https:\/\/mktfactory.com\/blog\/super-intelligenza-artificiale\/\" target=\"_blank\" rel=\"noopener noreferrer\">intelligenza artificiale<\/a> molte cose sono cambiate.<\/p>\n<p>Infatti come avevo previsto la tecnologia sta accelerando sempre di pi\u00f9.<\/p>\n<p>E l\u2019intelligenza artificiale \u00e8 nella <a href=\"https:\/\/www.ft.com\/content\/8ec09bea-3b38-11e7-821a-6027b8a20f23\" target=\"_blank\" rel=\"noopener noreferrer\">maggior parte dei prodotti Google<\/a>.<\/p>\n<p>E\u2019 talmente importante che \u00e8 la priorit\u00e0 numero 1 di Google, Apple, Microsoft, Amazon, Facebook e company.<\/p>\n<p>E tu puoi farne a meno?<\/p>\n<h3>Dal Podcast<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-372\" src=\"http:\/\/mktfactory.com\/podcast\/wp-content\/uploads\/2016\/12\/Lingegno-batte-il-capitale-1024x640.jpg\" alt=\"l'ingegno-batte-il-capitale\" width=\"1024\" height=\"640\"\/><\/p>\n<p><iframe loading=\"lazy\" style=\"border: none;\" src=\"\/\/html5-player.libsyn.com\/embed\/episode\/id\/4941535\/height\/100\/width\/640\/theme\/standard\/autonext\/no\/thumbnail\/no\/autoplay\/no\/preload\/no\/no_addthis\/no\/direction\/backward\/no-cache\/true\/\" width=\"640\" height=\"100\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><\/p><center><a class=\"button\" href=\"https:\/\/itunes.apple.com\/ch\/podcast\/mkt-podcast\/id957794295?l=en\">Ascolta su iTunes<\/a><\/center>Puoi ascoltare l&#8217;episodio su <a href=\"https:\/\/itunes.apple.com\/ch\/podcast\/mkt-podcast\/id957794295?l=en\">iTunes<\/a> | <a href=\"http:\/\/www.stitcher.com\/podcast\/mkt-podcast\">Stitcher<\/a> oppure <a href=\"http:\/\/feeds.feedburner.com\/MktPodcast\">tramite RSS<\/a> (non-iTunes feed)<p><\/p>\n<h3>CONCLUSIONE<\/h3>\n<p>Viviamo in un mondo in cui la tecnologia ha eliminato le distante. Un mondo in cui miliardi di persone a migliaia di chilometri di distanza ti possono rubare il lavoro.<\/p>\n<p>Per diventare degli esperti riconosciuti bisogna impegnarsi. Avere degli obiettivi ben precisi e perseguirli con determinazione.<\/p>\n<p>Comunque, se ti \u00e8 piaciuto questo articolo ti consiglio di unirti alla <a href=\"https:\/\/www.mktfactory.com\/newsletter\/\">cerchia degli Insiders<\/a> per ricevere sempre le strategie migliori prima degli altri.<\/p>\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2020\/09\/Come-diventare-esperti-di-settore-683x1024.jpg\" alt=\"Come diventare esperti di settore\" class=\"wp-image-3317\" srcset=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2020\/09\/Come-diventare-esperti-di-settore-683x1024.jpg 683w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2020\/09\/Come-diventare-esperti-di-settore-200x300.jpg 200w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2020\/09\/Come-diventare-esperti-di-settore-600x900.jpg 600w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2020\/09\/Come-diventare-esperti-di-settore.jpg 735w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>In ogni settore c&#8217;\u00e8 una piccola fetta di fenomeni che prende tutti i guadagni, lasciando agli altri solo briciole. Chi sono questi fenomeni? Questi Guuuurrruuuu. Sono i cosiddetti leader di mercato. Solitamente una manciata di essi controlla l&#8217;80% del mercato. E&#8217; gente ultra specializzata. Super competitiva. Nella maggior parte dei casi hanno dedicato la loro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2476,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[80,17,77],"tags":[106,133,101],"class_list":{"0":"post-2463","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-leadership","8":"category-marketing","9":"category-startup","10":"tag-leadership","11":"tag-market","12":"tag-networking","13":"entry"},"featured_image_src":"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2017\/11\/Come-diventare-un-esperto-nel-proprio-settore.png","featured_image_src_square":"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2017\/11\/Come-diventare-un-esperto-nel-proprio-settore.png","author_info":{"display_name":"Dino Gojanovic","author_link":"https:\/\/mktfactory.com\/blog\/author\/mkt\/"},"_links":{"self":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts\/2463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/comments?post=2463"}],"version-history":[{"count":22,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts\/2463\/revisions"}],"predecessor-version":[{"id":3319,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts\/2463\/revisions\/3319"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/media\/2476"}],"wp:attachment":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/media?parent=2463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/categories?post=2463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/tags?post=2463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}