{"id":3350,"date":"2021-05-27T14:08:44","date_gmt":"2021-05-27T12:08:44","guid":{"rendered":"https:\/\/mktfactory.com\/blog\/?p=3350"},"modified":"2022-08-13T12:13:00","modified_gmt":"2022-08-13T10:13:00","slug":"come-diventare-un-nomade-digitale","status":"publish","type":"post","link":"https:\/\/mktfactory.com\/blog\/come-diventare-un-nomade-digitale\/","title":{"rendered":"Come diventare un Nomade Digitale"},"content":{"rendered":"\n<p>Dopo la pandemia il mondo del lavoro e&#8217; totalmente cambiato. Una figura professionale risulta essere piu&#8217; in voga delle altre. <\/p>\n\n\n\n<p>E&#8217; il nomade digitale. <\/p>\n\n\n\n<p>Per lui viaggiare per il mondo e lavorare dalle spiagge tropicali e&#8217; normale come bere un bicchiere d&#8217;acqua. <\/p>\n\n\n\n<p>Gli basta un computer, una connessione ad internet, uno smartphone e qualche app essenziale ed e&#8217; pronto per fatturare.<\/p>\n\n\n\n<p>Conosce i segreti del marketing digitale. E&#8217; familiari con i termini inglesi tipo Sales Funnel, Conversion rate o Mailing list. <\/p>\n\n\n\n<p>E il mondo sembra accorgersi di questo nuovo trend lavorativo.<\/p>\n\n\n\n<p>I paesi pi\u00f9 svegli hanno da subito iniziato a prepare tutta l&#8217;infrastruttura per accoglierli. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2021\/05\/Come-diventare-un-nomade-digitale-683x1024.jpg\" alt=\"Come diventare un nomade digitale\" class=\"wp-image-3355\" srcset=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2021\/05\/Come-diventare-un-nomade-digitale-683x1024.jpg 683w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2021\/05\/Come-diventare-un-nomade-digitale-200x300.jpg 200w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2021\/05\/Come-diventare-un-nomade-digitale-600x900.jpg 600w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2021\/05\/Come-diventare-un-nomade-digitale.jpg 735w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<p>Dalla piccola Croazia che offre una carta visa apposita per invogliare i nomadi digitali a lavorare dalla bellissima costa.<\/p>\n\n\n\n<p>All&#8217;Estonia che offre la residenza digitale e la possibilit\u00e0 di aprire e gestire il proprio business totalmente da remoto. <\/p>\n\n\n\n<p>Ma comunque, se anche tu vuoi diventare un nomade digitale, ti devi preparare. <\/p>\n\n\n\n<p>Come prima cosa, hai bisogno di conoscere persone come te, che hanno la tua stessa ambizione e con le quali puoi condividere questa avventura. <\/p>\n\n\n\n<p>Sul Internet e&#8217; pieno di gruppi che raccoglie i nomadi digitali da tutto il mondo. <\/p>\n\n\n\n<p>Una delle meglio organizzate e&#8217; quella su Nomad List. Puoi entrare in contatto con questa comunit\u00e0 e farti aiutare.<\/p>\n\n\n\n<p>Per iniziare avrai bisogno di queste cose:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Identifica le tue competenze <\/h3>\n\n\n\n<p>Per fare il nomade digitale devi avere certe competenze che siano fattibili da remoto. Non puoi fare la cassiera di un supermercato stando alla Seyshelles. <\/p>\n\n\n\n<p>Quindi la cosa migliore da fare e&#8217; stilare una lista di tutte le cose che sai fare e che possono essere fatte con un computer e una connessione ad internet.  <\/p>\n\n\n\n<p>Un&#8217;altra maniera per scoprire le tue competenze chiave e&#8217; con il Feedback Analysis suggerito da Peter Drucker. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Identifica le esigenze del mercato <\/h3>\n\n\n\n<p>Ovviamente, saper fare le cose non e&#8217; sufficiente per riuscire ad avere delle entrate. Devi anche soddisfare le esigenze del mercato. <\/p>\n\n\n\n<p><strong>Devi fornire un prodotto o servizio che la gente sia disposta a comprare. <\/strong><\/p>\n\n\n\n<p>Altrimenti rischi di lavorare a gratis. Il che non promette un roseo futuro. Per fare una ricerca di mercato <a href=\"https:\/\/mktfactory.com\/blog\/come-fare-una-ricerca-di-mercato\/\" data-type=\"post\" data-id=\"953\">ti consiglio questo articolo<\/a>. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Diventa un Freelancer <\/h3>\n\n\n\n<p>Per fare il Freelancer oggigiorno e&#8217; alquanto semplice. La tecnologia in questi ultimi anni ha letteralmente spianato le barriere d&#8217;entrata. Il problema e&#8217; che, se e&#8217; facile per te allora lo e&#8217; anche per un miliardo di indiani. <\/p>\n\n\n\n<p>Dopotutto, se hanno un computer, una connessione ad internet sono in competizione con te. Perci\u00f2 devi avere una <a href=\"https:\/\/mktfactory.com\/podcast\/naval-ravikant-e76\/\" target=\"_blank\" rel=\"noreferrer noopener\">conoscenza specifica, come suggerisce Naval<\/a>. <\/p>\n\n\n\n<p>Quella cosa che sai fare meglio degli altri, che fai senza sforzo, ed e&#8217; gradita dal mercato. Quella cosa che non e&#8217; facile insegnare, perch\u00e9 se lo fosse allora avresti facile concorrenza e saresti al punto di partenza. <\/p>\n\n\n\n<p>Non posso dirti cosa sia questa cosa. Solo tu conosci le tue passioni e le tue abilit\u00e0. Ti consiglio comunque di rifletterci sopra. <\/p>\n\n\n\n<p>Prenditi un po&#8217; di tempo per l&#8217;autoanalisi, se trovi questa tua conoscenza specifica hai risolto un enorme problema per te stesso. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Promuovi te stesso sulle piattaforme di social media<\/h3>\n\n\n\n<p>I social media sono il modo migliore per promuovere la tua attivit\u00e0. \u00c8 uno strumento potente che pu\u00f2 aiutarti a far crescere la tua attivit\u00e0 e raggiungere nuovi clienti. Ti aiuta anche a rimanere in contatto con i tuoi attuali clienti fornendo loro aggiornamenti su ci\u00f2 che sta accadendo nel panorama mondiale.<\/p>\n\n\n\n<p>\u00c8 importante sapere quali canali di social media sono i migliori per la tua attivit\u00e0 e quali ti daranno i maggiori vantaggi.<\/p>\n\n\n\n<p>Di seguito sono riportati alcuni dei migliori canali social per la crescita del business:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Facebook: Facebook ha 1 miliardo di utenti attivi ogni giorno. Questo lo rende una piattaforma ideale per le aziende che vogliono entrare in contatto con persone interessate al loro prodotto o servizio.<\/li><li>Twitter: Twitter \u00e8 un potente strumento per raggiungere persone che potrebbero non essere su Facebook, come celebrit\u00e0 o potenziali clienti al di fuori del tuo paese.<\/li><li>Instagram: Instagram \u00e8 una popolare app per la condivisione di foto. Ti aiuta a connetterti con marchi, celebrit\u00e0, leader di mercato, amici, familiari e altro ancora.<\/li><li>TikTok: TikTok \u00e8 una popolare app di social media che consente agli utenti di creare, guardare e condividere video di 15 secondi girati sui cellulari.<\/li><\/ul>\n\n\n\n<p>E poi c&#8217;\u00e8 anche Snapchat, YouTube, Twitch, Reddit, e altri.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Trovare il lavoro da remoto <\/h3>\n\n\n\n<p>Il fatto che l&#8217;Italia abbia un tasso di disoccupazione alto non dovrebbe preoccuparti se sai come trovare lavoro su internet. <\/p>\n\n\n\n<p>Dai una occhiata a questi siti web che offrono lavori da remoto.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.flexjobs.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">FlexJobs<\/a> <\/li><li><a href=\"https:\/\/justremote.co\/\" target=\"_blank\" rel=\"noreferrer noopener\">Just Remote<\/a> <\/li><li><a href=\"https:\/\/weworkremotely.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">We Work Remotely<\/a> <\/li><li><a href=\"https:\/\/remote.co\/\" target=\"_blank\" rel=\"noreferrer noopener\">Remote.co<\/a> <\/li><li><a href=\"https:\/\/remotive.io\/\" target=\"_blank\" rel=\"noreferrer noopener\">Remotive<\/a> <\/li><\/ul>\n\n\n\n<p>Se non sai fare nessuno dei lavori qui pubblicati allora puoi benissimo fare un corso online ed imparare il mestiere. <\/p>\n\n\n\n<p>Iscriviti alla newsletter e ti faccio sapere quando esce il mio prossimo corso online.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Crea il tuo business <\/h3>\n\n\n\n<p>Come nomade digitale hai tantissime opzioni su dove aprire il tuo business. <\/p>\n\n\n\n<p>Ti consiglio comunque paesi con una tassazione vantaggiosa. C&#8217;\u00e8 un enorme differenza tra uno stato che ti chiede il 40% degli incassi ed uno stato che te ne chiede il 10%. <\/p>\n\n\n\n<p>Quel 30% in pi\u00f9 che metti nelle tue tasche ogni anno fanno molto comodo quando devi competere con altre aziende nello stesso mercato. <\/p>\n\n\n\n<p>Pensa se tu fossi un atleta che pu\u00f2 comprare solo un pasto al giorno mentre gli altri atleti mangiano tre pasti al giorno. <\/p>\n\n\n\n<p>Chi credi che alla fine vincer\u00e0? Ovviamente chi ha pi\u00f9 energia.<\/p>\n\n\n\n<p> Quindi le aziende che hanno pi\u00f9 liquidit\u00e0 sono pi\u00f9 competitive perch\u00e9 possono permettersi pi\u00f9 marketing, pi\u00f9 personale, pi\u00f9 investimenti in ricerca e sviluppo.<\/p>\n\n\n\n<p> L&#8217;unica maniera sensata di competere con altre aziende su scala globale e&#8217; di essere tassati come loro o meno di loro. Di certo non pi\u00f9 di loro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Decidi la tua prima destinazione <\/h3>\n\n\n\n<p>Ci sono dei ottimi siti per scovare localit\u00e0 interessanti come <a rel=\"noreferrer noopener\" href=\"http:\/\/numbeo.com\" target=\"_blank\">numbeo.com<\/a> e <a rel=\"noreferrer noopener\" href=\"https:\/\/nomadlist.com\/\" target=\"_blank\">nomadlist.com<\/a> <\/p>\n\n\n\n<p>Entrambi utili per sapere gli effettivi costi da citt\u00e0 a citt\u00e0. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2022\/08\/nomade_viaggio_bellissimo.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2022\/08\/nomade_viaggio_bellissimo.jpg\" alt=\"\" class=\"wp-image-3445\" srcset=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2022\/08\/nomade_viaggio_bellissimo.jpg 800w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2022\/08\/nomade_viaggio_bellissimo-300x300.jpg 300w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2022\/08\/nomade_viaggio_bellissimo-150x150.jpg 150w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2022\/08\/nomade_viaggio_bellissimo-768x768.jpg 768w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2022\/08\/nomade_viaggio_bellissimo-600x600.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Decidi il tuo stile di vita <\/h3>\n\n\n\n<p>I tuoi genitori non ti possono consigliare in questo periodo storico. Il mondo e&#8217; totalmente diverso da ci\u00f2 che era quando loro erano giovani.<\/p>\n\n\n\n<p>Il mondo digitale e&#8217; nuovo e perlopi\u00f9 sconosciuto alla maggioranza.<\/p>\n\n\n\n<p>Quindi tocca a te inventarti uno stile di vita che sia su misura. Quello del nomade digitale e&#8217; una vera e proprio novit\u00e0 e sta a te trovare cio&#8217; che funziona. <\/p>\n\n\n\n<p>In fin dei conti stanno tutti sperimentando. <\/p>\n\n\n\n<p>Ma non sei di certo il primo nomade digitale, ordunque puoi prendere ispirazione dagli altri tuoi colleghi internazionali. <\/p>\n\n\n\n<p>Insomma, cerca di vedere il tuo stile di vita come un continuo Work in progress. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Prima di partire elimina le spese superflue <\/h3>\n\n\n\n<p>Non puoi partire con il pensiero sereno se lasci certe cose in sospeso. Elimina o metti in pausa abbonamenti che non ti serviranno all&#8217;estero. <\/p>\n\n\n\n<p>Ad esempio, se hai una abbonamento ad internet a casa e sai che starai fuori all&#8217;estero per un anno. Perche&#8217; pagare il fornitore IT per 12 mesi e non utilizzare il servizio? Chiamali e chiedi una momentanea sospensione. <\/p>\n\n\n\n<p>Cosi per tutti i costi se puoi. Per quelle cose che non e&#8217; possibile sospendere, trova la maniera per pagare le loro bollette online. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fatti un assicurazione sanitaria <\/h3>\n\n\n\n<p>I rischi nella vita bisogna prenderli, ma non troppi. Per questo una buona assicurazione sanitaria internazionale ti pu\u00f2 portare sonni pi\u00f9 tranquilli. Ad esempio, Nomad Insurance. <\/p>\n\n\n\n<p>Ma leggi per bene i loro contratti. Non sai mai cosa e&#8217; coperto e cosa no. <\/p>\n\n\n\n<p>Ci sono clausole trabocchetto tipo, se sei ricoverato per una malattia che gi\u00e0 avevi in precedenza allora non ti coprono. <\/p>\n\n\n\n<p>Oppure hanno proprio la lista delle malattia che non coprono. Ad esempio il Covid. <\/p>\n\n\n\n<p>Insomma guarda il tuo caso e poi comportati di conseguenza. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Metti 6 mesi di soldi da parte <\/h3>\n\n\n\n<p>Non partire con pochi spiccioli. <\/p>\n\n\n\n<p>Non hai idea di quanto sono comodi i soldi in un paese dove non conosci la lingua e non conosci nessuno nel momento del bisogno. <\/p>\n\n\n\n<p>Non contare sul fatto che ci sono i tuoi genitori che possono sempre farti un bonifico se occorre. La banca per una qualsiasi stupidaggine ti pu\u00f2 sospendere il conto o la carta. <\/p>\n\n\n\n<p>La VISA, MasterCard o Amex ti possono sospendere la carta nel venerd\u00ec sera, e che fino al luned\u00ec non riuscirai a rintracciare nessuno. <\/p>\n\n\n\n<p>Puoi ancora smarrire o rompere il telefono e non riuscire ad utilizzare il tuo conto online o altre cose.<\/p>\n\n\n\n<p>Insomma, hai capito il succo del discorso. <\/p>\n\n\n\n<p>Tieni da parte un po&#8217; di contante. Tieni diversi conti correnti con banche diverse. Tieni diverse carte. Anche prepagate possibilmente.<\/p>\n\n\n\n<p>L&#8217;ho imparato sulla mia pelle. Nel momento cruciale qualcosa si blocca. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Copertura telefonica internazionale <\/h3>\n\n\n\n<p>Non pensare che con il tuo modesto abbonamento Telecom riuscirai ad avere vita facile all&#8217;estero. Se sei fuori dall&#8217;Europa ti prosciugheranno con il roaming. <\/p>\n\n\n\n<p>Dovrai per forza contemplare un abbonamento che non ti abbandoni una volta messo piede fuori casa. <\/p>\n\n\n\n<p>Oppure se sai da subito il paese in cui andrai, informati sul loro migliore operatore telefonico e cerca di ottenere una prepagata locale. <\/p>\n\n\n\n<p>Smartphone a due schede e&#8217; utilissimo. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.mktfactory.com\/newsletter\/\"><img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"842\" src=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2017\/06\/1.png\" alt=\"Diventa un insider, iscriviti alla newsletter\" class=\"wp-image-2703\" srcset=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2017\/06\/1.png 567w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2017\/06\/1-202x300.png 202w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Crea un&#8217;account su Airbnb <\/h3>\n\n\n\n<p>Volente o nolente avrai bisogno di Airbnb se vuoi essere un nomade digitale. Tanto vale che crei da subito un account. <\/p>\n\n\n\n<p>Per intenderci, Airbnb e&#8217; un sito web dove puoi trovare alloggi ovunque al mondo. Con prezzi per ogni genere di tasca. <\/p>\n\n\n\n<p>Ovviamente leggi sempre le recensioni. Non prenotare posti con zero recensioni. <\/p>\n\n\n\n<p>Sopratutto se sei nelle zone pericolose. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Crea un account bancario digitale <\/h3>\n\n\n\n<p>Alcune buone opzioni sono: <\/p>\n\n\n\n<p><a href=\"https:\/\/n26.com\/it-it\" target=\"_blank\" rel=\"noreferrer noopener\">N26<\/a> <\/p>\n\n\n\n<p>N26 \u00e8 una banca online creata per i millennial, viaggiatori frequenti e nomadi digitali. <\/p>\n\n\n\n<p><a href=\"https:\/\/www.revolut.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Revolut<\/a> <\/p>\n\n\n\n<p>Revolut e&#8217; un app con che ti offre la possibilit\u00e0 di tenere un conto online con 28 monete diverse. <\/p>\n\n\n\n<p><a href=\"https:\/\/wise.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Wise<\/a> <\/p>\n\n\n\n<p>Wise, (in precedenza TransferWise) \u00e8 un servizio online per inviare denaro all&#8217;estero con costi minori di una normale banca. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Installa queste app per ogni eventualit\u00e0<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Google Translate <\/li><li>Google Maps <\/li><li>Airbnb <\/li><li>Couchsurf <\/li><li>Booking<\/li><li>Uber <\/li><li>Flixbus <\/li><li>Ada Health<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Conclusione<\/h3>\n\n\n\n<p>Essere nomade digitale e&#8217; uno stile di vita reso possibile dalla rivoluzione digitale di questi anni.<\/p>\n\n\n\n<p>Con la pandemia e&#8217; stato tutto accelerato e tutti adesso vogliono essere in grado di lavorare da remoto.<\/p>\n\n\n\n<p>Ma non e&#8217; per tutti e sopratutto non e&#8217; per gli impreparati. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2022\/08\/piscina_hotel_nomade_digitale.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2022\/08\/piscina_hotel_nomade_digitale.jpg\" alt=\"\" class=\"wp-image-3447\" srcset=\"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2022\/08\/piscina_hotel_nomade_digitale.jpg 800w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2022\/08\/piscina_hotel_nomade_digitale-300x300.jpg 300w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2022\/08\/piscina_hotel_nomade_digitale-150x150.jpg 150w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2022\/08\/piscina_hotel_nomade_digitale-768x768.jpg 768w, https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2022\/08\/piscina_hotel_nomade_digitale-600x600.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Dopo la pandemia il mondo del lavoro e&#8217; totalmente cambiato. Una figura professionale risulta essere piu&#8217; in voga delle altre. E&#8217; il nomade digitale. Per lui viaggiare per il mondo e lavorare dalle spiagge tropicali e&#8217; normale come bere un bicchiere d&#8217;acqua. Gli basta un computer, una connessione ad internet, uno smartphone e qualche app [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3355,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[84,77],"tags":[248,247,249,246,250,251],"class_list":{"0":"post-3350","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-business-online","8":"category-startup","9":"tag-freelancer","10":"tag-lavoro-da-remoto","11":"tag-n26","12":"tag-nomade-digitale","13":"tag-revolut","14":"tag-wise","15":"entry"},"featured_image_src":"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2021\/05\/Come-diventare-un-nomade-digitale-600x400.jpg","featured_image_src_square":"https:\/\/mktfactory.com\/blog\/wp-content\/uploads\/2021\/05\/Come-diventare-un-nomade-digitale-600x600.jpg","author_info":{"display_name":"Dino Gojanovic","author_link":"https:\/\/mktfactory.com\/blog\/author\/mkt\/"},"_links":{"self":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts\/3350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/comments?post=3350"}],"version-history":[{"count":13,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts\/3350\/revisions"}],"predecessor-version":[{"id":3448,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/posts\/3350\/revisions\/3448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/media\/3355"}],"wp:attachment":[{"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/media?parent=3350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/categories?post=3350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mktfactory.com\/blog\/wp-json\/wp\/v2\/tags?post=3350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}