{"id":987,"date":"2023-03-25T15:39:26","date_gmt":"2023-03-25T15:39:26","guid":{"rendered":"https:\/\/mktfactory.com\/podcast\/?p=987"},"modified":"2023-03-29T22:42:31","modified_gmt":"2023-03-29T22:42:31","slug":"non-reagire-a-tutto-ep-87","status":"publish","type":"post","link":"https:\/\/mktfactory.com\/podcast\/non-reagire-a-tutto-ep-87\/","title":{"rendered":"Non reagire a tutto &#8211; Ep. #87"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/mktfactory.com\/podcast\/wp-content\/uploads\/2023\/03\/Non-reagire-a-tutto-Ep.-87-MKT-Podcast.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1300\" src=\"https:\/\/mktfactory.com\/podcast\/wp-content\/uploads\/2023\/03\/Non-reagire-a-tutto-Ep.-87-MKT-Podcast.jpg\" alt=\"Non reagire a tutto. MKT Podcast\" class=\"wp-image-991\" srcset=\"https:\/\/mktfactory.com\/podcast\/wp-content\/uploads\/2023\/03\/Non-reagire-a-tutto-Ep.-87-MKT-Podcast.jpg 900w, https:\/\/mktfactory.com\/podcast\/wp-content\/uploads\/2023\/03\/Non-reagire-a-tutto-Ep.-87-MKT-Podcast-208x300.jpg 208w, https:\/\/mktfactory.com\/podcast\/wp-content\/uploads\/2023\/03\/Non-reagire-a-tutto-Ep.-87-MKT-Podcast-709x1024.jpg 709w, https:\/\/mktfactory.com\/podcast\/wp-content\/uploads\/2023\/03\/Non-reagire-a-tutto-Ep.-87-MKT-Podcast-768x1109.jpg 768w, https:\/\/mktfactory.com\/podcast\/wp-content\/uploads\/2023\/03\/Non-reagire-a-tutto-Ep.-87-MKT-Podcast-600x867.jpg 600w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/figure>\n\n\n\n<p>La vita pu\u00f2 essere analizzata da pi\u00f9 angolazioni.<\/p>\n\n\n\n<p>Uno pu\u00f2 essere quello dell&#8217;azione e reazione o causa ed effetto.<\/p>\n\n\n\n<p><br>La legge di causa ed effetto \u00e8 una legge universale che afferma specificamente che ogni singola azione nell&#8217;universo produce una reazione, qualunque essa sia.<\/p>\n\n\n\n<p><br>Quindi c&#8217;\u00e8 una causa e l&#8217;effetto che produce.<\/p>\n\n\n\n<p><br>Non ci pu\u00f2 essere un effetto senza una causa e non ci pu\u00f2 essere una causa senza un effetto.<\/p>\n\n\n\n<p><br>Anche tu fai parte di questa legge universale.<\/p>\n\n\n\n<p><br>Anche tu sei la causa e l&#8217;effetto.<\/p>\n\n\n\n<p><br>Come vedi te stesso nel grande schema delle cose?<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<iframe loading=\"lazy\" title=\"Libsyn Player\" style=\"border: none\" src=\"\/\/html5-player.libsyn.com\/embed\/episode\/id\/26338368\/height\/90\/theme\/custom\/thumbnail\/yes\/direction\/backward\/render-playlist\/no\/custom-color\/000000\/\" height=\"90\" width=\"100%\" scrolling=\"no\" allowfullscreen=\"\" webkitallowfullscreen=\"\" mozallowfullscreen=\"\" oallowfullscreen=\"\" msallowfullscreen=\"\"><\/iframe>\n\n\n\n<p><\/p>\n\n\n\n<p>Puoi ascoltare la puntata su <a href=\"https:\/\/open.spotify.com\/show\/0Y6aO7wIgXRW0Tq2enjQ5C\"> Spotify<\/a> &#8211; <a href=\"https:\/\/podcasts.apple.com\/it\/podcast\/mkt-podcast\/id957794295?l=it\">Apple Podcasts<\/a> &#8211; <a href=\"https:\/\/podcasts.google.com\/?feed=aHR0cDovL2ZlZWRzLmZlZWRidXJuZXIuY29tL01rdFBvZGNhc3Q%3D\">Google Podcast<\/a> <\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><br>Sei l&#8217;azione alla quale gli altri reagiscono oppure sei la reazione alle azioni altrui?<\/p>\n\n\n\n<p><br>Ti ritrovi spesso a pensare che gli altri siano la causa dei tuoi problemi?<\/p>\n\n\n\n<p><br>Loro sono la causa e tu subisci gli effetti negativi.<\/p>\n\n\n\n<p><br>Marito e moglie sono sposati da 30 anni. Lei causa la maggior parte dei suoi problemi.<\/p>\n\n\n\n<p><br>Lei agisce, lui reagisce.<\/p>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/356YIv7xleA\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n\n\n\n<p><br>Nei film di James Bond quando i cattivi lo provocano, lui non ha mai una reazione emozionale.<\/p>\n\n\n\n<p><br>Come se non fosse minimamente scalfito dall&#8217;insulto, dalla minaccia o dalla percossa fisica.<\/p>\n\n\n\n<p><br>Loro desideravano piegare il suo spirito prima di piegare il suo corpo.<\/p>\n\n\n\n<p><br>Volevano da lui una reazione da vittima.<\/p>\n\n\n\n<p><br>Invece hanno ottenuto un contro-attacco sotto forma di feedback.<\/p>\n\n\n\n<p><br>Non reagendo innesca un nuovo ciclo di causa ed effetto.<\/p>\n\n\n\n<p><br>Invertendo i ruoli.<\/p>\n\n\n\n<p><br>Il fatto che lui non reagisce emotivamente dimostra alla controparte di non essere turbato.<\/p>\n\n\n\n<p><br>Di non percepire la minaccia.<\/p>\n\n\n\n<p><br>Se James Bond non reagisce significa che la minaccia non \u00e8 all&#8217;altezza del compito.<\/p>\n\n\n\n<p><br>Che il cattivo non \u00e8 poi cos\u00ec tanto cattivo come crede di essere.<\/p>\n\n\n\n<p><br>Che non \u00e8 credibile quanto crede di essere.<\/p>\n\n\n\n<p><br>Che non \u00e8 forte o intelligente quanto crede di essere.<\/p>\n\n\n\n<p><br>Inoltre implica il fatto che forse James Bond ha una carta nascosta.<\/p>\n\n\n\n<p><br>Il <a href=\"https:\/\/mktfactory.com\/podcast\/come-ridurre-costi-di-marketing-e75\/\" data-type=\"post\" data-id=\"833\">marketing<\/a> \u00e8 fatto da azione e reazione.<\/p>\n\n\n\n<p><br>Per cambiare il <a href=\"https:\/\/mktfactory.com\/blog\/consigli-di-marketing-per-business\/\" data-type=\"URL\" data-id=\"https:\/\/mktfactory.com\/blog\/consigli-di-marketing-per-business\/\">comportamento della tua audience<\/a> tu devi generare l&#8217;azione.<\/p>\n\n\n\n<p><br>Sta a loro reagire emotivamente.<\/p>\n\n\n\n<p><br>Se non reagiscono le tue azioni non hanno avuto effetto e dovresti tentare qualcos&#8217;altro.<\/p>\n\n\n\n<p><br>Tu crei un <a href=\"https:\/\/mktfactory.com\/podcast\/come-riproporre-vecchi-contenuti-e79\/\" data-type=\"post\" data-id=\"879\">contenuto<\/a> e lo invii al tuo pubblico.<\/p>\n\n\n\n<p><br>Loro lo ignorano completamente ma in cambio a te ritorna un <a href=\"https:\/\/mktfactory.com\/podcast\/zero-moment-of-truth-zmot-e67\/\" data-type=\"post\" data-id=\"748\">feedback<\/a> negativo che urta la tua psiche.<\/p>\n\n\n\n<p><br>Perch\u00e9 ti comunica che ci\u00f2 che hai creato non \u00e8 abbastanza.<\/p>\n\n\n\n<p><br>Sta a te decidere se vuoi ripetere il ciclo con dei miglioramenti oppure fare come la maggior parte \u2026<\/p>\n\n\n\n<p><br>Abbandonare.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/mktfactory.com\/newsletter\/\"><img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"842\" src=\"https:\/\/mktfactory.com\/podcast\/wp-content\/uploads\/2020\/11\/1.png\" alt=\"Diventa un insider\" class=\"wp-image-787\" srcset=\"https:\/\/mktfactory.com\/podcast\/wp-content\/uploads\/2020\/11\/1.png 567w, https:\/\/mktfactory.com\/podcast\/wp-content\/uploads\/2020\/11\/1-202x300.png 202w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La vita pu\u00f2 essere analizzata da pi\u00f9 angolazioni. Uno pu\u00f2 essere quello dell&#8217;azione e reazione o causa ed effetto. La legge di causa ed effetto \u00e8 una legge universale che afferma specificamente che ogni singola azione nell&#8217;universo produce una reazione, qualunque essa sia. Quindi c&#8217;\u00e8 una causa e l&#8217;effetto che produce. Non ci pu\u00f2 essere [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":991,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[3],"tags":[162,164,165,163],"class_list":{"0":"post-987","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-podcast","8":"tag-azione","9":"tag-causa","10":"tag-effetto","11":"tag-reazione","12":"entry"},"featured_image_src":"https:\/\/mktfactory.com\/podcast\/wp-content\/uploads\/2023\/03\/Non-reagire-a-tutto-Ep.-87-MKT-Podcast-600x400.jpg","featured_image_src_square":"https:\/\/mktfactory.com\/podcast\/wp-content\/uploads\/2023\/03\/Non-reagire-a-tutto-Ep.-87-MKT-Podcast-600x600.jpg","author_info":{"display_name":"Dino Gojanovic","author_link":"https:\/\/mktfactory.com\/podcast\/author\/mkt\/"},"_links":{"self":[{"href":"https:\/\/mktfactory.com\/podcast\/wp-json\/wp\/v2\/posts\/987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mktfactory.com\/podcast\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mktfactory.com\/podcast\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mktfactory.com\/podcast\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mktfactory.com\/podcast\/wp-json\/wp\/v2\/comments?post=987"}],"version-history":[{"count":9,"href":"https:\/\/mktfactory.com\/podcast\/wp-json\/wp\/v2\/posts\/987\/revisions"}],"predecessor-version":[{"id":998,"href":"https:\/\/mktfactory.com\/podcast\/wp-json\/wp\/v2\/posts\/987\/revisions\/998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mktfactory.com\/podcast\/wp-json\/wp\/v2\/media\/991"}],"wp:attachment":[{"href":"https:\/\/mktfactory.com\/podcast\/wp-json\/wp\/v2\/media?parent=987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mktfactory.com\/podcast\/wp-json\/wp\/v2\/categories?post=987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mktfactory.com\/podcast\/wp-json\/wp\/v2\/tags?post=987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}